{"id":10447,"count":1,"description":"","link":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/","name":"Kh-22 \"Tempest\"","slug":"kh-22-tempest","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kh-22 &quot;Tempest&quot; \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kh-22 &quot;Tempest&quot; \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@defensearab\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/\",\"url\":\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/\",\"name\":\"Kh-22 \\\"Tempest\\\" \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\",\"isPartOf\":{\"@id\":\"https:\/\/defense-arab.com\/news\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\/\/defense-arab.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kh-22 \\\"Tempest\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/defense-arab.com\/news\/#website\",\"url\":\"https:\/\/defense-arab.com\/news\/\",\"name\":\"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\",\"description\":\"\u0634\u0624\u0648\u0646 \u0627\u0644\u062f\u0641\u0627\u0639 \u0648\u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0639\u0633\u0643\u0631\u064a \u0627\u0644\u0639\u0631\u0628\u064a \u0648\u0627\u0644\u0639\u0627\u0644\u0645\u064a\",\"publisher\":{\"@id\":\"https:\/\/defense-arab.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/defense-arab.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/defense-arab.com\/news\/#organization\",\"name\":\"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\",\"url\":\"https:\/\/defense-arab.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/defense-arab.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/defense-arab.com\/news\/wp-content\/uploads\/2020\/08\/logo-2.png\",\"contentUrl\":\"https:\/\/defense-arab.com\/news\/wp-content\/uploads\/2020\/08\/logo-2.png\",\"width\":142,\"height\":111,\"caption\":\"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a\"},\"image\":{\"@id\":\"https:\/\/defense-arab.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/defensearab\",\"https:\/\/x.com\/defensearab\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kh-22 \"Tempest\" \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/","og_locale":"ar_AR","og_type":"article","og_title":"Kh-22 \"Tempest\" \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","og_url":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/","og_site_name":"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","twitter_card":"summary_large_image","twitter_site":"@defensearab","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/","url":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/","name":"Kh-22 \"Tempest\" \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","isPartOf":{"@id":"https:\/\/defense-arab.com\/news\/#website"},"breadcrumb":{"@id":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/defense-arab.com\/news\/tag\/kh-22-tempest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/defense-arab.com\/news\/"},{"@type":"ListItem","position":2,"name":"Kh-22 \"Tempest\""}]},{"@type":"WebSite","@id":"https:\/\/defense-arab.com\/news\/#website","url":"https:\/\/defense-arab.com\/news\/","name":"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","description":"\u0634\u0624\u0648\u0646 \u0627\u0644\u062f\u0641\u0627\u0639 \u0648\u0627\u0644\u0634\u0623\u0646 \u0627\u0644\u0639\u0633\u0643\u0631\u064a \u0627\u0644\u0639\u0631\u0628\u064a \u0648\u0627\u0644\u0639\u0627\u0644\u0645\u064a","publisher":{"@id":"https:\/\/defense-arab.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/defense-arab.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/defense-arab.com\/news\/#organization","name":"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a","url":"https:\/\/defense-arab.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/defense-arab.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/defense-arab.com\/news\/wp-content\/uploads\/2020\/08\/logo-2.png","contentUrl":"https:\/\/defense-arab.com\/news\/wp-content\/uploads\/2020\/08\/logo-2.png","width":142,"height":111,"caption":"\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u062f\u0641\u0627\u0639 \u0627\u0644\u0639\u0631\u0628\u064a"},"image":{"@id":"https:\/\/defense-arab.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/defensearab","https:\/\/x.com\/defensearab"]}]}},"_links":{"self":[{"href":"https:\/\/defense-arab.com\/news\/wp-json\/wp\/v2\/tags\/10447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defense-arab.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/defense-arab.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/defense-arab.com\/news\/wp-json\/wp\/v2\/posts?tags=10447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}